{"id":2404,"date":"2018-05-03T09:30:02","date_gmt":"2018-05-03T07:30:02","guid":{"rendered":"https:\/\/adoa.es\/?p=2404"},"modified":"2018-05-03T11:43:33","modified_gmt":"2018-05-03T09:43:33","slug":"achegase-o-dia-da-nai","status":"publish","type":"post","link":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/","title":{"rendered":"Achegase o d\u00eda da nai"},"content":{"rendered":"<p>Achegase o dia da nai e que mellor momento para agradecerlles todo o que nos deron, empezando pola vida, e non solo a nosa sen\u00f3n que ademais sacrifican a seu vida por conseguir que sexamos o mais felices posible. Por \u00e9llo e por elas en Adoa invit\u00e1moste a que goces deste gran d\u00eda con nos.<br \/>\nVos Esperamos este s\u00e1bado de 9:00 a 14:00 e de 15:30 a 21:00.<\/p>\n<p>FELIZ D\u00cdA DA NAI<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2390\" src=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre-225x300.jpg 225w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre-450x600.jpg 450w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre-529x705.jpg 529w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre.jpg 680w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2388\" src=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre2-225x300.jpg 225w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre2-450x600.jpg 450w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre2-529x705.jpg 529w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/dia-de-la-madre2.jpg 680w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2400\" src=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1-225x300.jpg 225w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1-450x600.jpg 450w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1-529x705.jpg 529w, https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1.jpg 680w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Achegase o dia da nai e que mellor momento para agradecerlles todo o que nos deron, empezando pola vida, e non solo a nosa sen\u00f3n que ademais sacrifican a seu vida por conseguir que sexamos o mais felices posible. Por \u00e9llo e por elas en Adoa invit\u00e1moste a que goces deste gran d\u00eda con nos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-2404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogadoa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Achegase o d\u00eda da nai - Adoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Adoa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Adoa\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/#\\\/schema\\\/person\\\/35d2fcfb44bd235f3bfd1fe77587583e\"},\"headline\":\"Achegase o d\u00eda da nai\",\"datePublished\":\"2018-05-03T07:30:02+00:00\",\"dateModified\":\"2018-05-03T09:43:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/\"},\"wordCount\":80,\"image\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adoa.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/flor-dia-de-la-madre-1.jpg\",\"articleSection\":[\"Blog Adoa\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/\",\"url\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/\",\"name\":\"Achegase o d\u00eda da nai - Adoa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adoa.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/flor-dia-de-la-madre-1.jpg\",\"datePublished\":\"2018-05-03T07:30:02+00:00\",\"dateModified\":\"2018-05-03T09:43:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/#\\\/schema\\\/person\\\/35d2fcfb44bd235f3bfd1fe77587583e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adoa.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/flor-dia-de-la-madre-1.jpg\",\"contentUrl\":\"https:\\\/\\\/adoa.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/flor-dia-de-la-madre-1.jpg\",\"width\":680,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/achegase-o-dia-da-nai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/adoa.es\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Achegase o d\u00eda da nai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/adoa.es\\\/gl\\\/\",\"name\":\"Adoa\",\"description\":\"Centros de Xardiner\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adoa.es\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adoa.es\\\/gl\\\/#\\\/schema\\\/person\\\/35d2fcfb44bd235f3bfd1fe77587583e\",\"name\":\"Redacci\u00f3n Adoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n Adoa\"},\"url\":\"https:\\\/\\\/adoa.es\\\/gl\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Achegase o d\u00eda da nai - Adoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/","twitter_misc":{"Escrito por":"Redacci\u00f3n Adoa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#article","isPartOf":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/"},"author":{"name":"Redacci\u00f3n Adoa","@id":"https:\/\/adoa.es\/gl\/#\/schema\/person\/35d2fcfb44bd235f3bfd1fe77587583e"},"headline":"Achegase o d\u00eda da nai","datePublished":"2018-05-03T07:30:02+00:00","dateModified":"2018-05-03T09:43:33+00:00","mainEntityOfPage":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/"},"wordCount":80,"image":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#primaryimage"},"thumbnailUrl":"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1.jpg","articleSection":["Blog Adoa"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/","url":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/","name":"Achegase o d\u00eda da nai - Adoa","isPartOf":{"@id":"https:\/\/adoa.es\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#primaryimage"},"image":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#primaryimage"},"thumbnailUrl":"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1.jpg","datePublished":"2018-05-03T07:30:02+00:00","dateModified":"2018-05-03T09:43:33+00:00","author":{"@id":"https:\/\/adoa.es\/gl\/#\/schema\/person\/35d2fcfb44bd235f3bfd1fe77587583e"},"breadcrumb":{"@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#primaryimage","url":"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1.jpg","contentUrl":"https:\/\/adoa.es\/wp-content\/uploads\/2018\/05\/flor-dia-de-la-madre-1.jpg","width":680,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/adoa.es\/gl\/achegase-o-dia-da-nai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adoa.es\/gl\/"},{"@type":"ListItem","position":2,"name":"Achegase o d\u00eda da nai"}]},{"@type":"WebSite","@id":"https:\/\/adoa.es\/gl\/#website","url":"https:\/\/adoa.es\/gl\/","name":"Adoa","description":"Centros de Xardiner\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adoa.es\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/adoa.es\/gl\/#\/schema\/person\/35d2fcfb44bd235f3bfd1fe77587583e","name":"Redacci\u00f3n Adoa","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c529799beecac48200ac34adb8a1c55c975b3b637c1550ccf88c599186adf2be?s=96&d=mm&r=g","caption":"Redacci\u00f3n Adoa"},"url":"https:\/\/adoa.es\/gl\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/posts\/2404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/comments?post=2404"}],"version-history":[{"count":3,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/posts\/2404\/revisions"}],"predecessor-version":[{"id":2406,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/posts\/2404\/revisions\/2406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/media\/2400"}],"wp:attachment":[{"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/media?parent=2404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/categories?post=2404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adoa.es\/gl\/wp-json\/wp\/v2\/tags?post=2404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}